{"id":5084,"date":"2023-02-24T16:34:00","date_gmt":"2023-02-24T19:34:00","guid":{"rendered":"https:\/\/www.biolabfarma.com.br\/?post_type=imprensa&#038;p=5084"},"modified":"2024-12-17T08:40:26","modified_gmt":"2024-12-17T11:40:26","slug":"biolab-se-traslada-al-extranjero-y-prepara-su-entrada-en-ee-uu","status":"publish","type":"imprensa","link":"https:\/\/www.biolabeco.com.br\/es\/imprensa\/biolab-avanca-no-exterior-e-prepara-entrada-nos-eua\/","title":{"rendered":"Biolab avanza en el extranjero y prepara su entrada en EE.UU."},"content":{"rendered":"\n<p>A Biolab, uma das principais farmac\u00eauticas brasileiras, est\u00e1 ampliando exposi\u00e7\u00e3o ao mercado externo, ao mesmo tempo em que avan\u00e7a com os investimentos, agora calculados em quase R$ 1 bilh\u00e3o por causa do encarecimento de equipamentos e materiais de constru\u00e7\u00e3o, em um novo e moderno complexo industrial em Pouso Alegre (MG).<\/p>\n\n\n\n<p>Em janeiro, seis meses depois de comprar o laborat\u00f3rio canadense Exzell Pharma, dono de marcas como Swiss Naturals e Salinex, obteve o registro do Vonau Flash (ondansetrona), medicamento inovador contra n\u00e1usea e v\u00f4mito de dissolu\u00e7\u00e3o oral quase imediata, na Ar\u00e1bia Saudita. Com isso, abriu caminho para vender o rem\u00e9dio, que no mercado \u00e1rabe levar\u00e1 a marca Mundell, aos 22 pa\u00edses da Liga \u00c1rabe.\u00a0<br>\u00a0<br>A empresa j\u00e1 exportava o Vonau para Equador e Col\u00f4mbia e fornecia outro produto, o Encrise (vasopressina), usado no tratamento do choque s\u00e9ptico, \u00e0 Ar\u00e1bia Saudita. O pr\u00f3ximo passo \u00e9 levar o Encrise para pa\u00edses da Am\u00e9rica Central, M\u00e9xico, onde a distribui\u00e7\u00e3o deve ser feita por outra farmac\u00eautica brasileira, a Eurofarma, e Canad\u00e1.\u00a0<br>\u00a0<br>&#8220;Estamos buscando a aprova\u00e7\u00e3o para diferentes produtos no Canad\u00e1&#8221;, disse ao Valor o presidente e s\u00f3cio da Biolab, Cleiton de Castro Marques. Segundo ele, no mercado internacional, a estrat\u00e9gia \u00e9 chegar a pa\u00edses de moeda forte, como Estados Unidos. E o maior mercado farmac\u00eautico do mundo \u00e9 um destino prov\u00e1vel j\u00e1 no curto ou m\u00e9dio prazo. &#8220;Vamos entrar com produtos menos complexos, mas com algum grau de inova\u00e7\u00e3o&#8221;, indicou.<br>\u00a0<br>A Biolab tem empresa aberta nos Estados Unidos e vem acumulando aprendizados no vizinho Canad\u00e1, onde chegou em 2017 com um centro pr\u00f3prio de pesquisa, desenvolvimento e inova\u00e7\u00e3o. Ali, todos os dossi\u00eas j\u00e1 s\u00e3o preparados conforme as exig\u00eancias da Food and Drug Administration (FDA), ag\u00eancia americana com atribui\u00e7\u00f5es semelhantes \u00e0s da Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa).\u00a0<br>\u00a0<br>Mas a exposi\u00e7\u00e3o de seus neg\u00f3cios ao mercado internacional ainda \u00e9 t\u00edmida, de cerca de 1% no ano passado, sem considerar a opera\u00e7\u00e3o canadense. Segundo Marques, a proposta \u00e9 usar a capacidade industrial no Brasil para atender aos demais mercados. A aquisi\u00e7\u00e3o no Canad\u00e1, explicou, levou em conta a robusta estrutura de vendas e distribui\u00e7\u00e3o da Exzell e o interesse do pa\u00eds em atrair investidores para o setor. &#8220;Ali, o investimento em farmac\u00eautica \u00e9 estrat\u00e9gico&#8221;, disse.\u00a0<br>\u00a0<br>O Brasil, sexto maior mercado de medicamentos do mundo, tamb\u00e9m tem atrativos, mas carece de uma pol\u00edtica efetiva de longo prazo para o setor, em sua avalia\u00e7\u00e3o. A Biolab \u00e9 s\u00f3cia da Eurofarma na Orygen, uma das &#8220;superfarmac\u00eauticas&#8221; idealizadas pelo governo federal para a produ\u00e7\u00e3o nacional de biossimilares. Desde sua cria\u00e7\u00e3o, o projeto perdeu outras duas participantes de peso, Crist\u00e1lia e Libbs, que seguem conduzindo pesquisas nessa \u00e1rea por conta pr\u00f3pria. &#8220;No modelo de PDP [Parceria para o Desenvolvimento Produtivo], n\u00e3o temos interesse&#8221;, afirmou.\u00a0<br>\u00a0<br>Ainda assim, a Biolab segue firme com o projeto de colocar em opera\u00e7\u00e3o, no pa\u00eds, sua maior unidade. Com or\u00e7amento inicial de R$ 500 milh\u00f5es, a nova f\u00e1brica foi anunciada em 2017. De l\u00e1 para c\u00e1, a estimativa de desembolsos para erguer o complexo industrial, que ter\u00e1 80 mil metros quadrados de \u00e1rea constru\u00edda, praticamente dobrou e se aproxima de R$ 1 bilh\u00e3o.\u00a0<br>\u00a0<br>&#8220;Al\u00e9m do aumento de custos com infraestrutura mesmo, com a\u00e7o e cimento, os equipamentos ficaram mais caros&#8221;, contou Marques. Duas \u00e1reas da nova unidade, que ser\u00e1 a maior da empresa, j\u00e1 est\u00e3o em opera\u00e7\u00e3o, mas a produ\u00e7\u00e3o efetiva de medicamentos deve ter in\u00edcio no segundo semestre de 2024, depois de todas as etapas de certifica\u00e7\u00e3o e aval da Anvisa.<br>\u00a0<br>A Biolab, que no ano passado faturou R$ 2,5 bilh\u00f5es, tem atua\u00e7\u00e3o diversificada, incluindo mercado PET, mas ainda encontra no portf\u00f3lio de cardiologia quase 50% de suas receitas. Com 45 lan\u00e7amentos no ano passado, tem em portf\u00f3lio 425 medicamentos de marca e gen\u00e9ricos, incluindo as diversas apresenta\u00e7\u00f5es, e 81 itens na linha veterin\u00e1ria (Avert). (Jornal Valor Econ\u00f4mico, Empresas\/SP \u2013 24\/02\/2023)<\/p>\n\n\n\n<p><a href=\"https:\/\/valor.globo.com\/empresas\/noticia\/2023\/02\/24\/biolab-avanca-no-exterior-e-prepara-entrada-nos-eua.ghtml\">https:\/\/valor.globo.com\/empresas\/noticia\/2023\/02\/24\/biolab-avanca-no-exterior-e-prepara-entrada-nos-eua.ghtml<\/a><\/p>\n","protected":false},"featured_media":0,"template":"","categories":[1577],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.4 (Yoast SEO v24.4) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biolab avan\u00e7a no exterior e prepara entrada nos EUA - Biolab &amp; Co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biolabeco.com.br\/es\/prensa\/biolab-se-traslada-al-extranjero-y-prepara-su-entrada-en-ee-uu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biolab avan\u00e7a no exterior e prepara entrada nos EUA\" \/>\n<meta property=\"og:description\" content=\"A Biolab, uma das principais farmac\u00eauticas brasileiras, est\u00e1 ampliando exposi\u00e7\u00e3o ao mercado externo, ao mesmo tempo em que avan\u00e7a com os investimentos, agora calculados em quase R$ 1 bilh\u00e3o por causa do encarecimento de equipamentos e materiais de constru\u00e7\u00e3o, em um novo e moderno complexo industrial em Pouso Alegre (MG). Em janeiro, seis meses depois [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.biolabeco.com.br\/es\/prensa\/biolab-se-traslada-al-extranjero-y-prepara-su-entrada-en-ee-uu\/\" \/>\n<meta property=\"og:site_name\" content=\"Biolab &amp; Co\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T11:40:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/\",\"url\":\"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/\",\"name\":\"Biolab avan\u00e7a no exterior e prepara entrada nos EUA - Biolab &amp; Co\",\"isPartOf\":{\"@id\":\"https:\/\/www.biolabeco.com.br\/#website\"},\"datePublished\":\"2023-02-24T19:34:00+00:00\",\"dateModified\":\"2024-12-17T11:40:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.biolabeco.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biolab avan\u00e7a no exterior e prepara entrada nos EUA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.biolabeco.com.br\/#website\",\"url\":\"https:\/\/www.biolabeco.com.br\/\",\"name\":\"Biolab\",\"description\":\"Na Biolab &amp; Co, ci\u00eancia e cuidado caminham juntos. Saiba como promovemos sa\u00fade com responsabilidade socioambiental e tecnologia.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.biolabeco.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Biolab avanza en el extranjero y prepara su entrada en EE.UU. - Biolab &amp; Co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biolabeco.com.br\/es\/prensa\/biolab-se-traslada-al-extranjero-y-prepara-su-entrada-en-ee-uu\/","og_locale":"es_ES","og_type":"article","og_title":"Biolab avan\u00e7a no exterior e prepara entrada nos EUA","og_description":"A Biolab, uma das principais farmac\u00eauticas brasileiras, est\u00e1 ampliando exposi\u00e7\u00e3o ao mercado externo, ao mesmo tempo em que avan\u00e7a com os investimentos, agora calculados em quase R$ 1 bilh\u00e3o por causa do encarecimento de equipamentos e materiais de constru\u00e7\u00e3o, em um novo e moderno complexo industrial em Pouso Alegre (MG). Em janeiro, seis meses depois [&hellip;]","og_url":"https:\/\/www.biolabeco.com.br\/es\/prensa\/biolab-se-traslada-al-extranjero-y-prepara-su-entrada-en-ee-uu\/","og_site_name":"Biolab &amp; Co","article_modified_time":"2024-12-17T11:40:26+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/","url":"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/","name":"Biolab avanza en el extranjero y prepara su entrada en EE.UU. - Biolab &amp; Co","isPartOf":{"@id":"https:\/\/www.biolabeco.com.br\/#website"},"datePublished":"2023-02-24T19:34:00+00:00","dateModified":"2024-12-17T11:40:26+00:00","breadcrumb":{"@id":"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.biolabeco.com.br\/en\/press\/biolab-moves-abroad-and-prepares-to-enter-the-usa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.biolabeco.com.br\/"},{"@type":"ListItem","position":2,"name":"Biolab avan\u00e7a no exterior e prepara entrada nos EUA"}]},{"@type":"WebSite","@id":"https:\/\/www.biolabeco.com.br\/#website","url":"https:\/\/www.biolabeco.com.br\/","name":"biolaboratorio","description":"En Biolab &amp; Co, la ciencia y el cuidado van de la mano. Descubra c\u00f3mo promovemos la salud con responsabilidad socioambiental y tecnolog\u00eda.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.biolabeco.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"}]}},"_links":{"self":[{"href":"https:\/\/www.biolabeco.com.br\/es\/wp-json\/wp\/v2\/imprensa\/5084"}],"collection":[{"href":"https:\/\/www.biolabeco.com.br\/es\/wp-json\/wp\/v2\/imprensa"}],"about":[{"href":"https:\/\/www.biolabeco.com.br\/es\/wp-json\/wp\/v2\/types\/imprensa"}],"version-history":[{"count":1,"href":"https:\/\/www.biolabeco.com.br\/es\/wp-json\/wp\/v2\/imprensa\/5084\/revisions"}],"predecessor-version":[{"id":8451,"href":"https:\/\/www.biolabeco.com.br\/es\/wp-json\/wp\/v2\/imprensa\/5084\/revisions\/8451"}],"wp:attachment":[{"href":"https:\/\/www.biolabeco.com.br\/es\/wp-json\/wp\/v2\/media?parent=5084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biolabeco.com.br\/es\/wp-json\/wp\/v2\/categories?post=5084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}